{"id":3683,"date":"2024-11-19T17:54:47","date_gmt":"2024-11-19T16:54:47","guid":{"rendered":"https:\/\/errotaldea.org\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-17-at-18.14.00-3.jpeg"},"modified":"2024-11-19T17:54:47","modified_gmt":"2024-11-19T16:54:47","slug":"whatsapp-image-2024-11-17-at-18-14-00-3","status":"inherit","type":"attachment","link":"https:\/\/errotaldea.org\/eu\/la-gran-recogida\/whatsapp-image-2024-11-17-at-18-14-00-3\/","title":{"rendered":"WhatsApp Irudia 2024-11-17 18.14.00etan (3)"},"author":52,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_EventAllDay":false,"_EventTimezone":"","_EventStartDate":"","_EventEndDate":"","_EventStartDateUTC":"","_EventEndDateUTC":"","_EventShowMap":false,"_EventShowMapLink":false,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"","_EventCurrencyCode":"","_EventCurrencyPosition":"","_EventDateTimeSeparator":"","_EventTimeRangeSeparator":"","_EventOrganizerID":[],"_EventVenueID":[],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"jetpack_post_was_ever_published":false},"class_list":["post-3683","attachment","type-attachment","status-inherit","hentry"],"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/errotaldea.org\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-17-at-18.14.00-3.jpeg'><img loading=\"lazy\" decoding=\"async\" width=\"135\" height=\"300\" src=\"https:\/\/errotaldea.org\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-17-at-18.14.00-3-135x300.jpeg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/errotaldea.org\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-17-at-18.14.00-3-135x300.jpeg 135w, https:\/\/errotaldea.org\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-17-at-18.14.00-3-461x1024.jpeg 461w, https:\/\/errotaldea.org\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-17-at-18.14.00-3-768x1707.jpeg 768w, https:\/\/errotaldea.org\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-17-at-18.14.00-3-691x1536.jpeg 691w, https:\/\/errotaldea.org\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-17-at-18.14.00-3-5x12.jpeg 5w, https:\/\/errotaldea.org\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-17-at-18.14.00-3.jpeg 918w\" sizes=\"(max-width: 135px) 100vw, 135px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":918,"height":2040,"file":"2024\/11\/WhatsApp-Image-2024-11-17-at-18.14.00-3.jpeg","filesize":523802,"sizes":{"medium":{"file":"WhatsApp-Image-2024-11-17-at-18.14.00-3-135x300.jpeg","width":135,"height":300,"filesize":15522,"mime_type":"image\/jpeg","source_url":"https:\/\/errotaldea.org\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-17-at-18.14.00-3-135x300.jpeg"},"large":{"file":"WhatsApp-Image-2024-11-17-at-18.14.00-3-461x1024.jpeg","width":461,"height":1024,"filesize":164993,"mime_type":"image\/jpeg","source_url":"https:\/\/errotaldea.org\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-17-at-18.14.00-3-461x1024.jpeg"},"thumbnail":{"file":"WhatsApp-Image-2024-11-17-at-18.14.00-3-150x150.jpeg","width":150,"height":150,"filesize":8459,"mime_type":"image\/jpeg","source_url":"https:\/\/errotaldea.org\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-17-at-18.14.00-3-150x150.jpeg"},"medium_large":{"file":"WhatsApp-Image-2024-11-17-at-18.14.00-3-768x1707.jpeg","width":768,"height":1707,"filesize":420818,"mime_type":"image\/jpeg","source_url":"https:\/\/errotaldea.org\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-17-at-18.14.00-3-768x1707.jpeg"},"1536x1536":{"file":"WhatsApp-Image-2024-11-17-at-18.14.00-3-691x1536.jpeg","width":691,"height":1536,"filesize":351052,"mime_type":"image\/jpeg","source_url":"https:\/\/errotaldea.org\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-17-at-18.14.00-3-691x1536.jpeg"},"trp-custom-language-flag":{"file":"WhatsApp-Image-2024-11-17-at-18.14.00-3-5x12.jpeg","width":5,"height":12,"filesize":340,"mime_type":"image\/jpeg","source_url":"https:\/\/errotaldea.org\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-17-at-18.14.00-3-5x12.jpeg"},"post-thumbnail":{"file":"WhatsApp-Image-2024-11-17-at-18.14.00-3-240x180.jpeg","width":240,"height":180,"filesize":13905,"mime_type":"image\/jpeg","source_url":"https:\/\/errotaldea.org\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-17-at-18.14.00-3-240x180.jpeg"},"edupress-large-thumbnail":{"file":"WhatsApp-Image-2024-11-17-at-18.14.00-3-780x400.jpeg","width":780,"height":400,"filesize":73396,"mime_type":"image\/jpeg","source_url":"https:\/\/errotaldea.org\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-17-at-18.14.00-3-780x400.jpeg"},"full":{"file":"WhatsApp-Image-2024-11-17-at-18.14.00-3.jpeg","width":918,"height":2040,"mime_type":"image\/jpeg","source_url":"https:\/\/errotaldea.org\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-17-at-18.14.00-3.jpeg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":3673,"source_url":"https:\/\/errotaldea.org\/wp-content\/uploads\/2024\/11\/WhatsApp-Image-2024-11-17-at-18.14.00-3.jpeg","_links":{"self":[{"href":"https:\/\/errotaldea.org\/eu\/wp-json\/wp\/v2\/media\/3683"}],"collection":[{"href":"https:\/\/errotaldea.org\/eu\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/errotaldea.org\/eu\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/errotaldea.org\/eu\/wp-json\/wp\/v2\/users\/52"}],"replies":[{"embeddable":true,"href":"https:\/\/errotaldea.org\/eu\/wp-json\/wp\/v2\/comments?post=3683"}]}}